{
    "id": 2476,
    "date": "2023-09-14T10:38:30",
    "date_gmt": "2023-09-14T13:38:30",
    "guid": {
        "rendered": "https:\/\/allpumps.com.ar\/nuevaweb\/?p=2476"
    },
    "modified": "2023-10-23T16:32:37",
    "modified_gmt": "2023-10-23T19:32:37",
    "slug": "revestimiento-de-caucho-o-alto-cromo-cuando-y-por-que-lineamientos-para-la-especificacion-y-seleccion-de-materiales-de-construccion-de-su-bomba-de-lodos",
    "status": "publish",
    "type": "post",
    "link": "https:\/\/allpumpseurope.com\/es\/revestimiento-de-caucho-o-alto-cromo-cuando-y-por-que-lineamientos-para-la-especificacion-y-seleccion-de-materiales-de-construccion-de-su-bomba-de-lodos\/",
    "title": {
        "rendered": "\u00bfRevestimiento de caucho o alto cromo?\u00a0\u00bfCu\u00e1ndo y por qu\u00e9? Lineamientos para la especificaci\u00f3n y selecci\u00f3n de materiales de construcci\u00f3n de su bomba de lodos"
    },
    "content": {
        "rendered": "<p>En los entornos industriales que dependen de bombas centr\u00edfugas para el manejo de lodos, garantizar la confiabilidad en la operaci\u00f3n de fluidos abrasivos y, en ocasiones, corrosivos, es siempre una prioridad. En este sentido, conocer la gama de opciones de materiales disponibles ofrece oportunidades para lograrlo.<br \/>\nLa mayor\u00eda de los fabricantes presentan dos opciones para la construcci\u00f3n de las piezas de desgaste de las bombas de lodos: caucho (SlurryPro 360) y acero de alto contenido de cromo (SlurryPro 331), este \u00faltimo a menudo con aleaciones ex\u00f3ticas para aplicaciones altamente corrosivas. El caucho y las aleaciones de alto cromo desempe\u00f1an roles espec\u00edficos, y la elecci\u00f3n adecuada se logra en colaboraci\u00f3n entre el proveedor de bombas experimentado y el cliente o el equipo de ingenier\u00eda, seg\u00fan las necesidades particulares de la aplicaci\u00f3n.<br \/>\nNo obstante, en ocasiones, surge la confusi\u00f3n al determinar qu\u00e9 material es el m\u00e1s apropiado. Un simple cambio en las circunstancias operativas puede impactar negativamente en la durabilidad y la confiabilidad, tanto de la bomba como de sus componentes de desgaste. A continuaci\u00f3n, presentamos algunos lineamientos esenciales para orientar la elecci\u00f3n de materiales de construcci\u00f3n en bombas centr\u00edfugas destinadas al manejo de lodos:<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone  wp-image-2477\" src=\"https:\/\/allpumps.com.ar\/nuevaweb\/wp-content\/uploads\/2023\/09\/Cuerpo-del-articulo-8-300x141.jpg\" alt=\"\" width=\"751\" height=\"353\" srcset=\"https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/09\/Cuerpo-del-articulo-8-300x141.jpg 300w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/09\/Cuerpo-del-articulo-8.jpg 735w\" sizes=\"(max-width: 751px) 100vw, 751px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Las piezas de caucho tienen menor costo de adquisici\u00f3n, son m\u00e1s livianas y constituyen la primera opci\u00f3n cuando se trata de lodos con peque\u00f1as\u00a0part\u00edculas, no filosas, que pueden rebotar en el material. Sin embargo, en aplicaciones con altas temperaturas y velocidad de bomba o presencia de grandes o filosos s\u00f3lidos, resulta conveniente utilizar un material de construcci\u00f3n m\u00e1s duro, como aleaci\u00f3n de alto cromo.<\/p>\n<p><strong>Las bombas SlurryPro se fabrican con partes de caucho o met\u00e1licas (aleaci\u00f3n de alto cromo)<\/strong><\/p>\n<p>Existen aplicaciones que justifican la selecci\u00f3n de una bomba h\u00edbrida, por ejemplo, con voluta con revestimiento de caucho e impulsor de aleaci\u00f3n de alto cromo. Esto es f\u00e1cil de advertir en aquellos casos en los que, por las cualidades del fluido, se emplea caucho, pero se requiere una alta presi\u00f3n de descarga que no permite la utilizaci\u00f3n del impulsor de este mismo material.<br \/>\nEn el caso de las bombas SlurryPro, estas cuentan con revestimientos de volutas e impulsores intercambiables, para asegurar flexibilidad en campo.\u00a0Si fuera necesario un cambio de materiales de construcci\u00f3n por modificaci\u00f3n del punto de servicio o propiedades del fluido, es posible realizarlo sin reemplazar el equipo.<\/p>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>En los entornos industriales que dependen de bombas centr\u00edfugas para el manejo de lodos, garantizar la confiabilidad en la operaci\u00f3n de fluidos abrasivos y, en ocasiones, corrosivos, es siempre una prioridad.<\/p>",
        "protected": false
    },
    "author": 1,
    "featured_media": 2479,
    "comment_status": "open",
    "ping_status": "open",
    "sticky": false,
    "template": "",
    "format": "standard",
    "meta": {
        "inline_featured_image": false,
        "footnotes": ""
    },
    "categories": [
        32
    ],
    "tags": [],
    "class_list": [
        "post-2476",
        "post",
        "type-post",
        "status-publish",
        "format-standard",
        "has-post-thumbnail",
        "hentry",
        "category-articulos-de-interes"
    ],
    "_links": {
        "self": [
            {
                "href": "https:\/\/allpumpseurope.com\/es\/wp-json\/wp\/v2\/posts\/2476",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/allpumpseurope.com\/es\/wp-json\/wp\/v2\/posts"
            }
        ],
        "about": [
            {
                "href": "https:\/\/allpumpseurope.com\/es\/wp-json\/wp\/v2\/types\/post"
            }
        ],
        "author": [
            {
                "embeddable": true,
                "href": "https:\/\/allpumpseurope.com\/es\/wp-json\/wp\/v2\/users\/1"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/allpumpseurope.com\/es\/wp-json\/wp\/v2\/comments?post=2476"
            }
        ],
        "version-history": [
            {
                "count": 2,
                "href": "https:\/\/allpumpseurope.com\/es\/wp-json\/wp\/v2\/posts\/2476\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 3381,
                "href": "https:\/\/allpumpseurope.com\/es\/wp-json\/wp\/v2\/posts\/2476\/revisions\/3381"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/allpumpseurope.com\/es\/wp-json\/wp\/v2\/media\/2479"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/allpumpseurope.com\/es\/wp-json\/wp\/v2\/media?parent=2476"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "category",
                "embeddable": true,
                "href": "https:\/\/allpumpseurope.com\/es\/wp-json\/wp\/v2\/categories?post=2476"
            },
            {
                "taxonomy": "post_tag",
                "embeddable": true,
                "href": "https:\/\/allpumpseurope.com\/es\/wp-json\/wp\/v2\/tags?post=2476"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}