{"id":2204,"date":"2023-08-30T14:03:00","date_gmt":"2023-08-30T17:03:00","guid":{"rendered":"https:\/\/allpumps.com.ar\/nuevaweb\/?p=2204"},"modified":"2023-10-23T16:34:13","modified_gmt":"2023-10-23T19:34:13","slug":"que-es-el-funcionamiento-en-seco-y-cuando-es-danino-para-las-bombas","status":"publish","type":"post","link":"https:\/\/allpumpseurope.com\/en\/que-es-el-funcionamiento-en-seco-y-cuando-es-danino-para-las-bombas\/","title":{"rendered":"What is dry running and when is it harmful to pumps?"},"content":{"rendered":"<p>El funcionamiento \u201cen seco\u201d de una bomba ocurre cuando su cabezal carece de l\u00edquido. Esto puede suceder en distintas situaciones: durante la operaci\u00f3n normal del equipo, en el ciclo de cebado inicial de la bomba, en la puesta en marcha sin antes haber abierto la v\u00e1lvula de succi\u00f3n o cuando el equipo queda operando sin fluido.<\/p>\n<p>Bombas afectadas por funcionamiento en seco<\/p>\n<p>A continuaci\u00f3n, detallaremos distintos equipos de bombeo haciendo \u00e9nfasis en su capacidad de operar en seco. Adem\u00e1s, listaremos una serie de precauciones recomendadas para cada uno a fin de evitar el impacto de esta.<\/p>\n<p>Bombas rotativas en general:<\/p>\n<table width=\"623\" cellspacing=\"0\" cellpadding=\"7\">\n<tbody>\n<tr valign=\"top\">\n<td width=\"378\">\n<p lang=\"es-AR\" align=\"center\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: large;\"><b>Tipo de bomba<\/b><\/span><\/span><\/p>\n<\/td>\n<td width=\"215\">\n<p lang=\"es-AR\" align=\"center\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: large;\"><b>Operaci\u00f3n en seco<\/b><\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"378\">\n<p lang=\"es-AR\" align=\"left\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: medium;\"><b>Bombas centrifugas horizontales, bombas a engranajes, a paletas, lobulares etc.<\/b> Las bombas rotativas tienden a generar temperatura en la zona de sellado si no tienen l\u00edquido de proceso para enfriar el sello mec\u00e1nico o la empaquetadura. Con poco tiempo de operaci\u00f3n generan roturas, requiriendo el retiro de servicio de la bomba. Es necesario siempre habilitar la v\u00e1lvula de succi\u00f3n antes de poner en marcha el equipo, as\u00ed como tambi\u00e9n asegurar la presencia de fluido en la bomba.<\/span><\/span><\/p>\n<\/td>\n<td width=\"215\">\n<p lang=\"es-AR\" align=\"left\"><img decoding=\"async\" class=\"wp-image-2210 aligncenter\" src=\"https:\/\/allpumps.com.ar\/nuevaweb\/wp-content\/uploads\/2023\/08\/marca-prohibida-300x300.png\" alt=\"\" width=\"39\" height=\"39\" srcset=\"https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-prohibida-300x300.png 300w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-prohibida-150x150.png 150w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-prohibida.png 512w\" sizes=\"(max-width: 39px) 100vw, 39px\" \/><\/p>\n<p lang=\"es-AR\" align=\"left\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: medium;\">Siempre habilitar la v\u00e1lvula de succi\u00f3n antes de poner en marcha el equipo. Asegurar la presencia de fluido en la bomba.<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"378\">\n<p lang=\"es-AR\" align=\"left\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: medium;\"><b>Bombas centr\u00edfugas sumergibles.<\/b> Si operan sin fluido, en poco tiempo generan altas temperaturas, quemando los elast\u00f3meros del sello y permitiendo el ingreso de fluido al motor. Es importante garantizar la presencia de l\u00edquido en la fosa e instalar con un control de nivel m\u00ednimo.<\/span><\/span><\/p>\n<\/td>\n<td width=\"215\">\n<p lang=\"es-AR\" align=\"left\"><img decoding=\"async\" class=\"wp-image-2210 aligncenter\" src=\"https:\/\/allpumps.com.ar\/nuevaweb\/wp-content\/uploads\/2023\/08\/marca-prohibida-300x300.png\" alt=\"\" width=\"39\" height=\"39\" srcset=\"https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-prohibida-300x300.png 300w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-prohibida-150x150.png 150w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-prohibida.png 512w\" sizes=\"(max-width: 39px) 100vw, 39px\" \/><\/p>\n<p lang=\"es-AR\" align=\"left\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: medium;\">Asegurar la presencia de fluido en la fosa. Instalar con control de nivel m\u00ednimo.<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"378\">\n<p lang=\"es-AR\" align=\"left\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: small;\"><b>Bombas a tornillo (cavidad progresiva). <\/b>Requieren de fluido para lubricar y reducir la fricci\u00f3n entre rotor y estator. Sin fluido, r\u00e1pidamente levantan temperatura hasta derretir el estator. Siempre es necesario habilitar la v\u00e1lvula de succi\u00f3n antes de poner en marcha el equipo y asegurar la presencia de fluido en la bomba.<\/span><\/span><\/p>\n<\/td>\n<td width=\"215\">\n<p lang=\"es-AR\" align=\"left\"><img decoding=\"async\" class=\"wp-image-2210 aligncenter\" src=\"https:\/\/allpumps.com.ar\/nuevaweb\/wp-content\/uploads\/2023\/08\/marca-prohibida-300x300.png\" alt=\"\" width=\"39\" height=\"39\" srcset=\"https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-prohibida-300x300.png 300w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-prohibida-150x150.png 150w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-prohibida.png 512w\" sizes=\"(max-width: 39px) 100vw, 39px\" \/><\/p>\n<p lang=\"es-AR\" align=\"left\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: medium;\">Siempre habilitar la v\u00e1lvula de succi\u00f3n antes de poner en marcha el equipo. Asegurar la presencia de fluido en la bomba.<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"378\">\n<p lang=\"es-AR\" align=\"left\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: medium;\"><b>Bombas a pist\u00f3n. <\/b>Requieren de fluido para lubricar las empaquetaduras de pist\u00f3n. Sin presencia de fluido, levantan temperatura hasta generar p\u00e9rdidas e ingreso de l\u00edquido a la lubricaci\u00f3n de los rodamientos, generando fallas. Es necesario siempre habilitar la v\u00e1lvula de succi\u00f3n antes de poner en marcha el equipo, as\u00ed como asegurar la presencia de fluido en la bomba.<\/span><\/span><\/p>\n<\/td>\n<td width=\"215\">\n<p lang=\"es-AR\" align=\"left\"><img decoding=\"async\" class=\"wp-image-2210 aligncenter\" src=\"https:\/\/allpumps.com.ar\/nuevaweb\/wp-content\/uploads\/2023\/08\/marca-prohibida-300x300.png\" alt=\"\" width=\"40\" height=\"40\" srcset=\"https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-prohibida-300x300.png 300w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-prohibida-150x150.png 150w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-prohibida.png 512w\" sizes=\"(max-width: 40px) 100vw, 40px\" \/><\/p>\n<p lang=\"es-AR\" align=\"left\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: medium;\">Siempre habilitar la v\u00e1lvula de succi\u00f3n antes de poner en marcha el equipo. Asegurar la presencia de fluido en la bomba.<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Precauciones para evitar el funcionamiento en seco<\/p>\n<p>Si bien existen muchas formas de garantizar la presencia de l\u00edquido en la bomba, a fin de evitar el funcionamiento en seco, detallaremos algunas de las m\u00e1s comunes:<\/p>\n<p>\u2022 Sensor de flujo o sensor de nivel de tanque de alimentaci\u00f3n. Con un sensor conectado al tablero de comando de la bomba, podemos asegurar que no se habilite el funcionamiento de la misma, salvo que haya presencia de fluido.\u00a0Esta soluci\u00f3n es relativamente sencilla y de bajo costo, pero con limitaciones cuando se trata de un fluido corrosivo.<br \/>\n\u2022 Protector inteligente de motor.\u00a0El protector de motor o sensor de consumo permite establecer par\u00e1metros de operaci\u00f3n del motor, con valores m\u00e1ximos y m\u00ednimos de consumo. Si la bomba comienza a operar fuera de este rango, el protector de motor env\u00eda una se\u00f1al de corte de suministro de corriente a la bomba, evitando as\u00ed el funcionamiento en seco. Estos sensores tambi\u00e9n proveen la posibilidad de comunicar al sistema de control de la planta a trav\u00e9s de cables o comunicaci\u00f3n\u00a0bluetooth.\u00a0Esto permite el monitoreo y el control de desv\u00edos en tiempo real.<br \/>\n\u2022 Sensor de temperatura en las partes cr\u00edticas de la bomba. Los sensores de este tipo permiten tambi\u00e9n alertar frente a una condici\u00f3n de temperatura desfavorable. Sin embargo, existe un margen de tiempo muy acotado hasta que se empiezan a da\u00f1ar algunos componentes de la bomba.<\/p>\n<p>De las tres alternativas, el detector de nivel es generalmente la m\u00e1s econ\u00f3mica para implementar. No obstante, sugerimos el sensor de consumo ya que detecta cualquier desv\u00edo r\u00e1pidamente y no requiere contacto con el fluido en movimiento.<\/p>\n<p>Bombas no afectadas por el funcionamiento en seco<\/p>\n<p>Las bombas no afectadas por el funcionamiento en seco, es decir que cuentan con la capacidad de operar sin fluido sin generar da\u00f1os a los componentes de la bomba, son las siguientes:<\/p>\n<p>&nbsp;<\/p>\n<table width=\"623\" cellspacing=\"0\" cellpadding=\"7\">\n<tbody>\n<tr valign=\"top\">\n<td width=\"378\">\n<p lang=\"es-AR\" align=\"left\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: medium;\"><b>Tipo de bomba <\/b><\/span><\/span><\/p>\n<\/td>\n<td width=\"215\">\n<p lang=\"es-AR\" align=\"left\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: medium;\"><b>Operaci\u00f3n en seco<\/b><\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"378\">\n<p lang=\"es-AR\" align=\"left\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: medium;\"><b>Bombas a diafragma<\/b><\/span><span style=\"font-size: small;\">. Las bombas a diafragma pueden operar sin fluido y desplazan aire. Esto permite que puedan cebarse solas en seco. En caso de quedar operando sin fluido, no afecta a ning\u00fan componente de la bomba. No se requiere v\u00e1lvula de pie para mantener la bomba cebada.<\/span><\/span><\/p>\n<\/td>\n<td width=\"215\">\n<p lang=\"es-AR\" align=\"left\"><img decoding=\"async\" class=\"wp-image-2211 aligncenter\" src=\"https:\/\/allpumps.com.ar\/nuevaweb\/wp-content\/uploads\/2023\/08\/marca-de-verificacion-300x300.png\" alt=\"\" width=\"40\" height=\"40\" srcset=\"https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-de-verificacion-300x300.png 300w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-de-verificacion-150x150.png 150w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-de-verificacion.png 512w\" sizes=\"(max-width: 40px) 100vw, 40px\" \/><\/p>\n<p lang=\"es-AR\" align=\"left\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: medium;\">No requieren v\u00e1lvula de pie para mantener la bomba cebada.<\/span><\/span><\/p>\n<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"378\">\n<p lang=\"es-AR\" align=\"left\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: medium;\"><b>Bombas de cavidad progresiva con estator met\u00e1lico<\/b>. A diferencia de las bombas con estator de caucho, las bombas de estator met\u00e1lico pueden operar en seco. As\u00ed tambi\u00e9n, es posible la operaci\u00f3n con fluidos de viscosidades iguales o superiores a 300 cp.<\/span><\/span><\/p>\n<\/td>\n<td width=\"215\">\n<img decoding=\"async\" class=\"wp-image-2211 aligncenter\" src=\"https:\/\/allpumps.com.ar\/nuevaweb\/wp-content\/uploads\/2023\/08\/marca-de-verificacion-300x300.png\" alt=\"\" width=\"40\" height=\"40\" srcset=\"https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-de-verificacion-300x300.png 300w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-de-verificacion-150x150.png 150w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-de-verificacion.png 512w\" sizes=\"(max-width: 40px) 100vw, 40px\" \/><\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"378\">\n<p lang=\"es-AR\" align=\"left\"><span style=\"font-family: Calibri, serif;\"><span style=\"font-size: medium;\"><b>Bombas perist\u00e1lticas.<\/b><\/span><span style=\"font-size: small;\"> Estas bombas son lubricadas desde el exterior de la manguera con un lubricante propio. No requieren fluido para operar. Pueden desplazar aire y cebarse en seco.<\/span><\/span><\/p>\n<\/td>\n<td width=\"215\">\n<img decoding=\"async\" class=\"wp-image-2211 aligncenter\" src=\"https:\/\/allpumps.com.ar\/nuevaweb\/wp-content\/uploads\/2023\/08\/marca-de-verificacion-300x300.png\" alt=\"\" width=\"40\" height=\"40\" srcset=\"https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-de-verificacion-300x300.png 300w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-de-verificacion-150x150.png 150w, https:\/\/allpumpseurope.com\/wp-content\/uploads\/2023\/08\/marca-de-verificacion.png 512w\" sizes=\"(max-width: 40px) 100vw, 40px\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Resumen<\/p>\n<p>En la actualidad, la mayor\u00eda de las bombas instaladas en plantas industriales, en caso de operar en seco o sin fluido de proceso, quedan fuera de servicio r\u00e1pidamente. Por este motivo, recomendamos la instalaci\u00f3n de medidas preventivas, a fin de evitar esta problem\u00e1tica.\u00a0El costo de implementaci\u00f3n es bajo en comparaci\u00f3n con el de la reparaci\u00f3n del equipo de bombeo. Al mismo tiempo, si contemplamos el costo de parada de proceso y potenciales derrames, el retorno sobre inversi\u00f3n es a\u00fan m\u00e1s r\u00e1pido.<br \/>\nPara aplicaciones donde la operaci\u00f3n en seco es altamente probable y frecuente, es recomendable evaluar una bomba que no pueda afrontar esta problem\u00e1tica.\u00a0Como ejemplos de aplicaciones, podemos citar descarga de camiones tanque, vaciado de barriles y operaciones de trasvase en general.<\/p>","protected":false},"excerpt":{"rendered":"<p>El funcionamiento \u201cen seco\u201d de una bomba ocurre cuando su cabezal carece de l\u00edquido. Esto puede suceder en distintas situaciones: durante la<\/p>","protected":false},"author":1,"featured_media":2208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[32],"tags":[],"class_list":["post-2204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-de-interes"],"_links":{"self":[{"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/posts\/2204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/comments?post=2204"}],"version-history":[{"count":4,"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/posts\/2204\/revisions"}],"predecessor-version":[{"id":3383,"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/posts\/2204\/revisions\/3383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/media\/2208"}],"wp:attachment":[{"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/media?parent=2204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/categories?post=2204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/tags?post=2204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}