{"id":74,"count":3,"description":"","link":"https:\/\/allpumpseurope.com\/en\/category\/articulos-de-interes\/mp\/","name":"MP","slug":"mp","taxonomy":"category","parent":32,"meta":[],"_links":{"self":[{"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/categories\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/categories\/32"}],"wp:post_type":[{"href":"https:\/\/allpumpseurope.com\/en\/wp-json\/wp\/v2\/posts?categories=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}